{"id":404,"date":"2020-09-23T15:07:39","date_gmt":"2020-09-23T13:07:39","guid":{"rendered":"http:\/\/www.portfolio.marmomac.com\/sotto-la-buccia-trovi-lanima-2\/"},"modified":"2020-09-28T16:59:13","modified_gmt":"2020-09-28T14:59:13","slug":"flourish","status":"publish","type":"page","link":"https:\/\/www.marmomac.com\/portfolio\/flourish\/","title":{"rendered":"Flourish"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1597757321777{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597757327347{margin-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1597912466508{margin-bottom: 10px !important;}&#8221;]<div data-post-id=\"12\" class=\"insert-page insert-page-12 \"><style type=\"text\/css\" data-type=\"vc_custom-css\">#titletist{\r\n    letter-spacing: 1px;\r\n}\r\n#linktitle{\r\n    letter-spacing: 1px;\r\n    font-weight:600;\r\n}<\/style><div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;The Italian Stone Theatre&#8221; font_container=&#8221;tag:h1|font_size:18|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_custom_heading text=&#8221;&gt; project&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.marmomac.com%2Fportfolio%2Fproject%2F|title:%3E%20project||&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_custom_heading text=&#8221;&gt; magazine&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2Fmagazine%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_custom_heading text=&#8221;&gt; marmomac.com&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2F|title:%3E%20marmomac.com|target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column offset=&#8221;vc_hidden-lg&#8221;][vc_row_inner][vc_column_inner][vc_custom_heading text=&#8221;The Italian Stone Theatre&#8221; font_container=&#8221;tag:h1|font_size:18|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; project&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.marmomac.com%2Fportfolio%2Fproject%2F|title:%3E%20project||&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; magazine&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2Fmagazine%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; marmomac.com&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2F|title:%3E%20marmomac.com|target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div><\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_type=&#8221;bg_color&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1597765947427{padding-top: 10px !important;padding-bottom: 10px !important;}&#8221; bg_color_value=&#8221;#000000&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597766022185{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee226a8be0ed&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597765784345{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee2275481d8a&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597824148186{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916384011{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;]<div id=\"advanced-tabs-desc-wrap-4781\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-6543 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab1\"  id=\"tab1\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6543 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">OPERA<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#tab2\"  id=\"tab2\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6543 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">DESIGNER<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#tab3\"  id=\"tab3\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6543 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">PRODUCTION<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab4\"  id=\"tab4\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6543 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">CATEGORY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-4781 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]Con la mia opera mi domando in che modo le forme naturali si trasformano quando il materiale della natura si modifica. Cosa succede quando un fiore diventa una pietra? Nelle <strong>foreste pietrificate<\/strong> possiamo vedere come gli alberi diventino pietra. Il legno diventa fossile e il materiale della pianta viene sostituito da silice, calcite, pirite e altri elementi inorganici.<br \/>\nLa parola <em>Flourish<\/em> significa svilupparsi in modo vigoroso.[\/vc_column_text][vc_custom_heading text=&#8221;\u201cLA NATURA \u00c8 INFLESSIBILE NELLA SUA GENEROSIT\u00c0. DARE UNA FORMA NATURALE A UN\u2019ALTRA \u00c8 UN GESTO DI GENTILEZZA\u201d&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Con la mia opera esploro il cambiamento di una forma vegetale che progredisce e si sviluppa in un altro materiale. Esploro il modo in cui il colore e le <strong>venature della pietra<\/strong> possono esprimere i diversi <em>pattern<\/em> e la natura organica del marmo. Cos\u00ec come un fiore apre i suoi petali e mostra la sua bellezza, con la mia opera rivelo la bellezza della pietra facendo \u201csbocciare\u201d il marmo.[\/vc_column_text]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;JON ISHERWOOD&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Il lavoro di Isherwood \u00e8 stato ampiamente esposto in musei pubblici e gallerie private in tutto il mondo, tra cui il Museo Peggy Guggenheim a Venezia, in Italia; il Museo McNay, a San Antonio, in Texas; e la Kunsthalle a Mannheim, in Germania. Il suo lavoro pu\u00f2 essere ritrovato in oltre <strong>25 collezioni pubbliche<\/strong>. Isherwood ha completato oltre 30 commesse nel settore privato e pubblico. Le sue sculture sono state <strong>recensite su The New York Times<\/strong>, Art in America, ArtNews, The Washington Post, Sculpture Magazine, Partisan Review e The Guardian UK. Ha rilasciato interviste tra cui quelle alle emittenti inglesi WAMC Public Radio e The Culture Show, BBC Television. Ha tenuto conferenze in numerosi college e universit\u00e0 negli Stati Uniti, in Europa e in Cina. Insegna al Bennington College VT ed \u00e8 il presidente del Digital Stone Project.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;1291&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:https%3A%2F%2Fwww.jonisherwood.com%2Fcurriculum-vitae||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:https%3A%2F%2Fwww.jonisherwood.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;GARFAGNANA INNOVAZIONE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;1299&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Primo Tonini, 82\/A<br \/>\n55034 Gramolazzo (LU) Italy<br \/>\nTel. +39 0583 390946<br \/>\n<a href=\"mailto:info@garfagnanainnovazione.it\">info@garfagnanainnovazione.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.garfagnanainnovazione.it%2F||target:%20_blank|&#8221; el_id=&#8221;linktitle&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]A cura di <em>Raffaello Galiotto<\/em><\/p>\n<p>La mostra <strong>Percorsi d\u2019Arte<\/strong>, giunta alla seconda edizione, vuole indagare il tema dell\u2019utilizzo delle macchine nella lavorazione artistica della pietra. Negli ultimi anni, con la diffusione delle tecnologie numeriche, sia l\u2019industria che l\u2019artigianato del<strong> settore litico<\/strong> si sono dotati di strumentazioni sempre pi\u00f9 performanti. Alcuni artisti internazionali che da tempo sperimentano le tecnologie numeriche per la lavorazione lapidea danno vita, in collaborazione con aziende italiane leader nella produzione di macchinari, software e utensili, ad opere sul tema della <strong>naturalit\u00e0 della pietra<\/strong>. Con l\u2019esposizione si intende evidenziare il rapporto tra l\u2019espressione artistica, la tecnologia e la pietra naturale.[\/vc_column_text]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-4781\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab1\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab1\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6543 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >OPERA<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]Con la mia opera mi domando in che modo le forme naturali si trasformano quando il materiale della natura si modifica. Cosa succede quando un fiore diventa una pietra? Nelle <strong>foreste pietrificate<\/strong> possiamo vedere come gli alberi diventino pietra. Il legno diventa fossile e il materiale della pianta viene sostituito da silice, calcite, pirite e altri elementi inorganici.<br \/>\nLa parola <em>Flourish<\/em> significa svilupparsi in modo vigoroso.[\/vc_column_text][vc_custom_heading text=&#8221;\u201cLA NATURA \u00c8 INFLESSIBILE NELLA SUA GENEROSIT\u00c0. DARE UNA FORMA NATURALE A UN\u2019ALTRA \u00c8 UN GESTO DI GENTILEZZA\u201d&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Con la mia opera esploro il cambiamento di una forma vegetale che progredisce e si sviluppa in un altro materiale. Esploro il modo in cui il colore e le <strong>venature della pietra<\/strong> possono esprimere i diversi <em>pattern<\/em> e la natura organica del marmo. Cos\u00ec come un fiore apre i suoi petali e mostra la sua bellezza, con la mia opera rivelo la bellezza della pietra facendo \u201csbocciare\u201d il marmo.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab2\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab2\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6543 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >DESIGNER<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;JON ISHERWOOD&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Il lavoro di Isherwood \u00e8 stato ampiamente esposto in musei pubblici e gallerie private in tutto il mondo, tra cui il Museo Peggy Guggenheim a Venezia, in Italia; il Museo McNay, a San Antonio, in Texas; e la Kunsthalle a Mannheim, in Germania. Il suo lavoro pu\u00f2 essere ritrovato in oltre <strong>25 collezioni pubbliche<\/strong>. Isherwood ha completato oltre 30 commesse nel settore privato e pubblico. Le sue sculture sono state <strong>recensite su The New York Times<\/strong>, Art in America, ArtNews, The Washington Post, Sculpture Magazine, Partisan Review e The Guardian UK. Ha rilasciato interviste tra cui quelle alle emittenti inglesi WAMC Public Radio e The Culture Show, BBC Television. Ha tenuto conferenze in numerosi college e universit\u00e0 negli Stati Uniti, in Europa e in Cina. Insegna al Bennington College VT ed \u00e8 il presidente del Digital Stone Project.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;1291&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:https%3A%2F%2Fwww.jonisherwood.com%2Fcurriculum-vitae||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:https%3A%2F%2Fwww.jonisherwood.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab3\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab3\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6543 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >PRODUCTION<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;GARFAGNANA INNOVAZIONE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;1299&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Primo Tonini, 82\/A<br \/>\n55034 Gramolazzo (LU) Italy<br \/>\nTel. +39 0583 390946<br \/>\n<a href=\"mailto:info@garfagnanainnovazione.it\">info@garfagnanainnovazione.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.garfagnanainnovazione.it%2F||target:%20_blank|&#8221; el_id=&#8221;linktitle&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab4\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab4\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6543 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >CATEGORY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]A cura di <em>Raffaello Galiotto<\/em><\/p>\n<p>La mostra <strong>Percorsi d\u2019Arte<\/strong>, giunta alla seconda edizione, vuole indagare il tema dell\u2019utilizzo delle macchine nella lavorazione artistica della pietra. Negli ultimi anni, con la diffusione delle tecnologie numeriche, sia l\u2019industria che l\u2019artigianato del<strong> settore litico<\/strong> si sono dotati di strumentazioni sempre pi\u00f9 performanti. Alcuni artisti internazionali che da tempo sperimentano le tecnologie numeriche per la lavorazione lapidea danno vita, in collaborazione con aziende italiane leader nella produzione di macchinari, software e utensili, ad opere sul tema della <strong>naturalit\u00e0 della pietra<\/strong>. Con l\u2019esposizione si intende evidenziare il rapporto tra l\u2019espressione artistica, la tecnologia e la pietra naturale.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916390943{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;]<div id=\"advanced-tabs-desc-wrap-1843\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-5219 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab5\"  id=\"tab5\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5219 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">FOTOGALLERY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#tab6\"  id=\"tab6\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5219 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">VIDEO<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab7\"  id=\"tab7\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5219 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">MAKING OF<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-1843 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-11370603446a049fd63a230\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-30269523736a049fd63a218 \" >[vc_single_image image=&#8221;1492&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1493&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1495&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1496&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1497&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-30269523736a049fd63a218').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-30269523736a049fd63a218').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-25728127276a049fd63a3ae\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-26238226776a049fd63a397 \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-26238226776a049fd63a397').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-26238226776a049fd63a397').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-1843\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab5\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab5\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5219 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >FOTOGALLERY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-17101716556a049fd639d60\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-32174319076a049fd639d43 \" >[vc_single_image image=&#8221;1492&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1493&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1495&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1496&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1497&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-32174319076a049fd639d43').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-32174319076a049fd639d43').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab6\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab6\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5219 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >VIDEO<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab7\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab7\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5219 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >MAKING OF<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-35449368736a049fd639e0f\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-14660812176a049fd639df8 \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-14660812176a049fd639df8').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-14660812176a049fd639df8').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597824148186{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597916374040{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-lg&#8221;]<div id=\"advanced-tabs-desc-wrap-3713\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-3119 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601305076214-0-4\"  id=\"1601305076214-0-4\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3119 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">OPERA<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#1601305076368-0-6\"  id=\"1601305076368-0-6\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3119 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">DESIGNER<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#1601305076716-0-3\"  id=\"1601305076716-0-3\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3119 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">PRODUCTION<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601305077079-0-5\"  id=\"1601305077079-0-5\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3119 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">CATEGORY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-3713 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]Con la mia opera mi domando in che modo le forme naturali si trasformano quando il materiale della natura si modifica. Cosa succede quando un fiore diventa una pietra? Nelle <strong>foreste pietrificate<\/strong> possiamo vedere come gli alberi diventino pietra. Il legno diventa fossile e il materiale della pianta viene sostituito da silice, calcite, pirite e altri elementi inorganici.<br \/>\nLa parola <em>Flourish<\/em> significa svilupparsi in modo vigoroso.[\/vc_column_text][vc_custom_heading text=&#8221;\u201cLA NATURA \u00c8 INFLESSIBILE NELLA SUA GENEROSIT\u00c0. DARE UNA FORMA NATURALE A UN\u2019ALTRA \u00c8 UN GESTO DI GENTILEZZA\u201d&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Con la mia opera esploro il cambiamento di una forma vegetale che progredisce e si sviluppa in un altro materiale. Esploro il modo in cui il colore e le <strong>venature della pietra<\/strong> possono esprimere i diversi <em>pattern<\/em> e la natura organica del marmo. Cos\u00ec come un fiore apre i suoi petali e mostra la sua bellezza, con la mia opera rivelo la bellezza della pietra facendo \u201csbocciare\u201d il marmo.[\/vc_column_text]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;JON ISHERWOOD&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Il lavoro di Isherwood \u00e8 stato ampiamente esposto in musei pubblici e gallerie private in tutto il mondo, tra cui il Museo Peggy Guggenheim a Venezia, in Italia; il Museo McNay, a San Antonio, in Texas; e la Kunsthalle a Mannheim, in Germania. Il suo lavoro pu\u00f2 essere ritrovato in oltre <strong>25 collezioni pubbliche<\/strong>. Isherwood ha completato oltre 30 commesse nel settore privato e pubblico. Le sue sculture sono state <strong>recensite su The New York Times<\/strong>, Art in America, ArtNews, The Washington Post, Sculpture Magazine, Partisan Review e The Guardian UK. Ha rilasciato interviste tra cui quelle alle emittenti inglesi WAMC Public Radio e The Culture Show, BBC Television. Ha tenuto conferenze in numerosi college e universit\u00e0 negli Stati Uniti, in Europa e in Cina. Insegna al Bennington College VT ed \u00e8 il presidente del Digital Stone Project.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;1291&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.jonisherwood.com%2Fcurriculum-vitae||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.jonisherwood.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;GARFAGNANA INNOVAZIONE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;1299&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Primo Tonini, 82\/A<br \/>\n55034 Gramolazzo (LU) Italy<br \/>\nTel. +39 0583 390946<br \/>\n<a href=\"mailto:info@garfagnanainnovazione.it\">info@garfagnanainnovazione.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.garfagnanainnovazione.it%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]A cura di <em>Raffaello Galiotto<\/em><\/p>\n<p>La mostra <strong>Percorsi d\u2019Arte<\/strong>, giunta alla seconda edizione, vuole indagare il tema dell\u2019utilizzo delle macchine nella lavorazione artistica della pietra. Negli ultimi anni, con la diffusione delle tecnologie numeriche, sia l\u2019industria che l\u2019artigianato del<strong> settore litico<\/strong> si sono dotati di strumentazioni sempre pi\u00f9 performanti. Alcuni artisti internazionali che da tempo sperimentano le tecnologie numeriche per la lavorazione lapidea danno vita, in collaborazione con aziende italiane leader nella produzione di macchinari, software e utensili, ad opere sul tema della <strong>naturalit\u00e0 della pietra<\/strong>. Con l\u2019esposizione si intende evidenziare il rapporto tra l\u2019espressione artistica, la tecnologia e la pietra naturale.[\/vc_column_text]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-3713\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601305076214-0-4\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601305076214-0-4\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3119 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >OPERA<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]Con la mia opera mi domando in che modo le forme naturali si trasformano quando il materiale della natura si modifica. Cosa succede quando un fiore diventa una pietra? Nelle <strong>foreste pietrificate<\/strong> possiamo vedere come gli alberi diventino pietra. Il legno diventa fossile e il materiale della pianta viene sostituito da silice, calcite, pirite e altri elementi inorganici.<br \/>\nLa parola <em>Flourish<\/em> significa svilupparsi in modo vigoroso.[\/vc_column_text][vc_custom_heading text=&#8221;\u201cLA NATURA \u00c8 INFLESSIBILE NELLA SUA GENEROSIT\u00c0. DARE UNA FORMA NATURALE A UN\u2019ALTRA \u00c8 UN GESTO DI GENTILEZZA\u201d&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Con la mia opera esploro il cambiamento di una forma vegetale che progredisce e si sviluppa in un altro materiale. Esploro il modo in cui il colore e le <strong>venature della pietra<\/strong> possono esprimere i diversi <em>pattern<\/em> e la natura organica del marmo. Cos\u00ec come un fiore apre i suoi petali e mostra la sua bellezza, con la mia opera rivelo la bellezza della pietra facendo \u201csbocciare\u201d il marmo.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601305076368-0-6\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601305076368-0-6\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3119 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >DESIGNER<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;JON ISHERWOOD&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Il lavoro di Isherwood \u00e8 stato ampiamente esposto in musei pubblici e gallerie private in tutto il mondo, tra cui il Museo Peggy Guggenheim a Venezia, in Italia; il Museo McNay, a San Antonio, in Texas; e la Kunsthalle a Mannheim, in Germania. Il suo lavoro pu\u00f2 essere ritrovato in oltre <strong>25 collezioni pubbliche<\/strong>. Isherwood ha completato oltre 30 commesse nel settore privato e pubblico. Le sue sculture sono state <strong>recensite su The New York Times<\/strong>, Art in America, ArtNews, The Washington Post, Sculpture Magazine, Partisan Review e The Guardian UK. Ha rilasciato interviste tra cui quelle alle emittenti inglesi WAMC Public Radio e The Culture Show, BBC Television. Ha tenuto conferenze in numerosi college e universit\u00e0 negli Stati Uniti, in Europa e in Cina. Insegna al Bennington College VT ed \u00e8 il presidente del Digital Stone Project.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;1291&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.jonisherwood.com%2Fcurriculum-vitae||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.jonisherwood.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601305076716-0-3\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601305076716-0-3\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3119 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >PRODUCTION<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;GARFAGNANA INNOVAZIONE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;1299&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Primo Tonini, 82\/A<br \/>\n55034 Gramolazzo (LU) Italy<br \/>\nTel. +39 0583 390946<br \/>\n<a href=\"mailto:info@garfagnanainnovazione.it\">info@garfagnanainnovazione.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.garfagnanainnovazione.it%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601305077079-0-5\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601305077079-0-5\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3119 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >CATEGORY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]A cura di <em>Raffaello Galiotto<\/em><\/p>\n<p>La mostra <strong>Percorsi d\u2019Arte<\/strong>, giunta alla seconda edizione, vuole indagare il tema dell\u2019utilizzo delle macchine nella lavorazione artistica della pietra. Negli ultimi anni, con la diffusione delle tecnologie numeriche, sia l\u2019industria che l\u2019artigianato del<strong> settore litico<\/strong> si sono dotati di strumentazioni sempre pi\u00f9 performanti. Alcuni artisti internazionali che da tempo sperimentano le tecnologie numeriche per la lavorazione lapidea danno vita, in collaborazione con aziende italiane leader nella produzione di macchinari, software e utensili, ad opere sul tema della <strong>naturalit\u00e0 della pietra<\/strong>. Con l\u2019esposizione si intende evidenziare il rapporto tra l\u2019espressione artistica, la tecnologia e la pietra naturale.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[vc_empty_space]<div id=\"advanced-tabs-desc-wrap-2425\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-8251 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601305086355-0-9\"  id=\"1601305086355-0-9\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8251 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">FOTOGALLERY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#1601305086686-0-5\"  id=\"1601305086686-0-5\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8251 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">VIDEO<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601305086856-0-6\"  id=\"1601305086856-0-6\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8251 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">MAKING OF<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-2425 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-25355240886a049fd63b053\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-39168607306a049fd63b03e \" >[vc_single_image image=&#8221;1492&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1493&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1495&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1496&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1497&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-39168607306a049fd63b03e').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-39168607306a049fd63b03e').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-20709848376a049fd63b1b7\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-32714100746a049fd63b19b \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-32714100746a049fd63b19b').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-32714100746a049fd63b19b').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-2425\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601305086355-0-9\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601305086355-0-9\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8251 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >FOTOGALLERY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-3718988066a049fd63ac08\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-7849823206a049fd63abe3 \" >[vc_single_image image=&#8221;1492&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1493&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1495&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1496&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1497&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-7849823206a049fd63abe3').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-7849823206a049fd63abe3').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601305086686-0-5\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601305086686-0-5\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8251 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >VIDEO<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601305086856-0-6\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601305086856-0-6\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8251 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >MAKING OF<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-5293436976a049fd63acbf\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-13159429306a049fd63aca7 \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-13159429306a049fd63aca7').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-13159429306a049fd63aca7').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1597757321777{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597757327347{margin-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1597912466508{margin-bottom: 10px !important;}&#8221;][\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_type=&#8221;bg_color&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1597765947427{padding-top: 10px !important;padding-bottom: 10px !important;}&#8221; bg_color_value=&#8221;#000000&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597766022185{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee226a8be0ed&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597765784345{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee2275481d8a&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597824148186{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916384011{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916390943{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221;&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-404","page","type-page","status-publish","hentry","description-off"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/pages\/404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/comments?post=404"}],"version-history":[{"count":0,"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/pages\/404\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/media?parent=404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}