{"id":311,"date":"2020-09-22T17:25:17","date_gmt":"2020-09-22T15:25:17","guid":{"rendered":"http:\/\/www.portfolio.marmomac.com\/everything-flows-2\/"},"modified":"2020-09-28T17:50:37","modified_gmt":"2020-09-28T15:50:37","slug":"walls","status":"publish","type":"page","link":"https:\/\/www.marmomac.com\/portfolio\/walls\/","title":{"rendered":"Walls"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1597757321777{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597757327347{margin-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1597912466508{margin-bottom: 10px !important;}&#8221;]<div data-post-id=\"12\" class=\"insert-page insert-page-12 \"><style type=\"text\/css\" data-type=\"vc_custom-css\">#titletist{\r\n    letter-spacing: 1px;\r\n}\r\n#linktitle{\r\n    letter-spacing: 1px;\r\n    font-weight:600;\r\n}<\/style><div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;The Italian Stone Theatre&#8221; font_container=&#8221;tag:h1|font_size:18|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_custom_heading text=&#8221;&gt; project&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.marmomac.com%2Fportfolio%2Fproject%2F|title:%3E%20project||&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_custom_heading text=&#8221;&gt; magazine&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2Fmagazine%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_custom_heading text=&#8221;&gt; marmomac.com&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2F|title:%3E%20marmomac.com|target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column offset=&#8221;vc_hidden-lg&#8221;][vc_row_inner][vc_column_inner][vc_custom_heading text=&#8221;The Italian Stone Theatre&#8221; font_container=&#8221;tag:h1|font_size:18|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; project&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.marmomac.com%2Fportfolio%2Fproject%2F|title:%3E%20project||&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; magazine&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2Fmagazine%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; marmomac.com&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2F|title:%3E%20marmomac.com|target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div><\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_type=&#8221;bg_color&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1597765947427{padding-top: 10px !important;padding-bottom: 10px !important;}&#8221; bg_color_value=&#8221;#000000&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597766022185{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee226a8be0ed&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597765784345{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee2275481d8a&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597824148186{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916384011{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;]<div id=\"advanced-tabs-desc-wrap-5000\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-2681 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab1\"  id=\"tab1\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-2681 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">OPERA<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#tab2\"  id=\"tab2\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-2681 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">DESIGNER<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#tab3\"  id=\"tab3\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-2681 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">PRODUCTION<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab4\"  id=\"tab4\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-2681 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">CATEGORY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-5000 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]L\u2019installazione \u201cWalls\u201d si domanda come la \u201cframmentazione\u201d sviluppi spazi a diverse scale, dalle micro alle macro. Fin dai tempi di <strong>Roma<\/strong>, complessa citt\u00e0 dell\u2019Impero Romano, le citt\u00e0 si sono sviluppate mediante suddivisioni per crescita e stratificazioni.[\/vc_column_text][vc_custom_heading text=&#8221;L\u2019EMERGERE DELLA \u201cPROPRIET\u00c0\u201d COMINCI\u00d2 CON LE \u201cDOPPIE MURA\u201d DELL\u2019IMPERATORE NERONE, CHE FINIRONO PER DIVENTARE LA BASE DEI TERRENI EDIFICABILI&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Analogamente possiamo tracciare l\u2019emergere dei minerali di marmo attraverso i processi di frammentazione e stratificazione. L\u2019installazione si accosta al marmo come<strong> linguaggio topografico<\/strong>, stratificando i cristalli da sola grazie ad una struttura suddivisoria. Inoltre, mira a rivelare le suddivisioni del marmo e la strategia genera una trama a pareti sottili sulla superficie in modo da simulare in <em>microscala<\/em> l\u2019essenza stessa della citt\u00e0. Le mura realizzano un confine, una rappresentazione dello spazio, o addirittura lo spazio stesso fondato dalla riconsiderazione del concetto di parete, elemento principale dell\u2019edificio.[\/vc_column_text]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;ALPER DERINBOGAZ&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Vincitore dell\u2019International Plan Award for <em>Innovative Architecture<\/em>, riconosciuto come \u201carchitetto emergente e influente\u201d, Derinbogaz si \u00e8 laureato all\u2019ITU, ha studiato presso l\u2019UCLA e si \u00e8 aggiudicato una <strong>Borsa di studio Fulbright<\/strong>. Ha vinto il Graduate Award per i suoi studi di Master e ha rappresentato la Turchia alla 14a Biennale di Architettura di Venezia nel suo anno di debutto presso il Padiglione turco nel 2014. Per i suoi recenti lavori gli \u00e8 stato assegnato l\u2019<strong>Architizer A+Award 2015<\/strong>. Attualmente insegna Design all\u2019ITU e dirige le attivit\u00e0 professionali del suo studio. Vincitore dell\u2019International Plan Award for Innovative Architecture, riconosciuto come \u201carchitetto emergente e influente\u201d, Derinbogaz si \u00e8 laureato all\u2019ITU, ha studiato presso l\u2019UCLA e si \u00e8 aggiudicato una Borsa di studio Fulbright. Ha vinto il Graduate Award per i suoi studi di Master e ha rappresentato la Turchia alla 14a Biennale di Architettura di Venezia nel suo anno di debutto presso il Padiglione turco nel 2014. Per i suoi recenti lavori gli \u00e8 stato assegnato l\u2019Architizer A+Award 2015. Attualmente insegna Design all\u2019ITU e dirige le attivit\u00e0 professionali del suo studio.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;691&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:http%3A%2F%2Fsalonarchitects.com%2Fabout%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:http%3A%2F%2Fsalonarchitects.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; linkedin&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:https%3A%2F%2Fwww.linkedin.com%2Fcompany%2Fsalon2%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;GARFAGNANA INNOVAZIONE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;694&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Primo Tonini 82\/A<br \/>\n55034 Gramolazzo, Lucca, Italia<br \/>\nTel.\/Fax +39 0583.390946<br \/>\n<a href=\"mailto:info@garfagnanainnovazione.it\">info@garfagnanainnovazione.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.garfagnanainnovazione.it%2Fit||target:%20_blank|&#8221; el_id=&#8221;linktitle&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]Curata da <em>Luca Molinari<\/em><\/p>\n<p>La pietra negli ultimi anni \u00e8 divenuta protagonista di numerose opere emblematiche della contemporaneit\u00e0 e ha inciso in modo significativo sul pensiero dei progettisti e sull\u2019evoluzione dei linguaggi architettonici attuali.\u00a0L\u2019introduzione di recenti sofisticate tecnologie di trasformazione ne ha inoltre permesso un<strong> impiego sostenibile<\/strong> favorendo il raggiungimento di nuovi livelli espressivi. La mostra\u00a0<em>Soul of City<\/em> indaga, attraverso la pietra, possibili visioni della citt\u00e0 contemporanea. \u00c8 un progetto di ricerca sull\u2019utilizzo della pietra che prende in prestito il tema del <strong>Congresso UIA 2017<\/strong> a Seoul. Sette studi internazionali di progettazione abbinati ad aziende del comparto marmifero italiano sfidano la materia da un punto di vista architettonico per rappresentare la propria idea di citt\u00e0.[\/vc_column_text]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-5000\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab1\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab1\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-2681 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >OPERA<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]L\u2019installazione \u201cWalls\u201d si domanda come la \u201cframmentazione\u201d sviluppi spazi a diverse scale, dalle micro alle macro. Fin dai tempi di <strong>Roma<\/strong>, complessa citt\u00e0 dell\u2019Impero Romano, le citt\u00e0 si sono sviluppate mediante suddivisioni per crescita e stratificazioni.[\/vc_column_text][vc_custom_heading text=&#8221;L\u2019EMERGERE DELLA \u201cPROPRIET\u00c0\u201d COMINCI\u00d2 CON LE \u201cDOPPIE MURA\u201d DELL\u2019IMPERATORE NERONE, CHE FINIRONO PER DIVENTARE LA BASE DEI TERRENI EDIFICABILI&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Analogamente possiamo tracciare l\u2019emergere dei minerali di marmo attraverso i processi di frammentazione e stratificazione. L\u2019installazione si accosta al marmo come<strong> linguaggio topografico<\/strong>, stratificando i cristalli da sola grazie ad una struttura suddivisoria. Inoltre, mira a rivelare le suddivisioni del marmo e la strategia genera una trama a pareti sottili sulla superficie in modo da simulare in <em>microscala<\/em> l\u2019essenza stessa della citt\u00e0. Le mura realizzano un confine, una rappresentazione dello spazio, o addirittura lo spazio stesso fondato dalla riconsiderazione del concetto di parete, elemento principale dell\u2019edificio.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab2\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab2\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-2681 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >DESIGNER<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;ALPER DERINBOGAZ&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Vincitore dell\u2019International Plan Award for <em>Innovative Architecture<\/em>, riconosciuto come \u201carchitetto emergente e influente\u201d, Derinbogaz si \u00e8 laureato all\u2019ITU, ha studiato presso l\u2019UCLA e si \u00e8 aggiudicato una <strong>Borsa di studio Fulbright<\/strong>. Ha vinto il Graduate Award per i suoi studi di Master e ha rappresentato la Turchia alla 14a Biennale di Architettura di Venezia nel suo anno di debutto presso il Padiglione turco nel 2014. Per i suoi recenti lavori gli \u00e8 stato assegnato l\u2019<strong>Architizer A+Award 2015<\/strong>. Attualmente insegna Design all\u2019ITU e dirige le attivit\u00e0 professionali del suo studio. Vincitore dell\u2019International Plan Award for Innovative Architecture, riconosciuto come \u201carchitetto emergente e influente\u201d, Derinbogaz si \u00e8 laureato all\u2019ITU, ha studiato presso l\u2019UCLA e si \u00e8 aggiudicato una Borsa di studio Fulbright. Ha vinto il Graduate Award per i suoi studi di Master e ha rappresentato la Turchia alla 14a Biennale di Architettura di Venezia nel suo anno di debutto presso il Padiglione turco nel 2014. Per i suoi recenti lavori gli \u00e8 stato assegnato l\u2019Architizer A+Award 2015. Attualmente insegna Design all\u2019ITU e dirige le attivit\u00e0 professionali del suo studio.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;691&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:http%3A%2F%2Fsalonarchitects.com%2Fabout%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:http%3A%2F%2Fsalonarchitects.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; linkedin&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:https%3A%2F%2Fwww.linkedin.com%2Fcompany%2Fsalon2%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab3\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab3\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-2681 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >PRODUCTION<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;GARFAGNANA INNOVAZIONE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;694&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Primo Tonini 82\/A<br \/>\n55034 Gramolazzo, Lucca, Italia<br \/>\nTel.\/Fax +39 0583.390946<br \/>\n<a href=\"mailto:info@garfagnanainnovazione.it\">info@garfagnanainnovazione.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.garfagnanainnovazione.it%2Fit||target:%20_blank|&#8221; el_id=&#8221;linktitle&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab4\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab4\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-2681 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >CATEGORY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]Curata da <em>Luca Molinari<\/em><\/p>\n<p>La pietra negli ultimi anni \u00e8 divenuta protagonista di numerose opere emblematiche della contemporaneit\u00e0 e ha inciso in modo significativo sul pensiero dei progettisti e sull\u2019evoluzione dei linguaggi architettonici attuali.\u00a0L\u2019introduzione di recenti sofisticate tecnologie di trasformazione ne ha inoltre permesso un<strong> impiego sostenibile<\/strong> favorendo il raggiungimento di nuovi livelli espressivi. La mostra\u00a0<em>Soul of City<\/em> indaga, attraverso la pietra, possibili visioni della citt\u00e0 contemporanea. \u00c8 un progetto di ricerca sull\u2019utilizzo della pietra che prende in prestito il tema del <strong>Congresso UIA 2017<\/strong> a Seoul. Sette studi internazionali di progettazione abbinati ad aziende del comparto marmifero italiano sfidano la materia da un punto di vista architettonico per rappresentare la propria idea di citt\u00e0.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916390943{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;]<div id=\"advanced-tabs-desc-wrap-4016\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-6728 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab5\"  id=\"tab5\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6728 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">FOTOGALLERY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#tab6\"  id=\"tab6\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6728 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">VIDEO<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab7\"  id=\"tab7\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6728 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">MAKING OF<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-4016 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-39119634266a04a004e7187\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-41023521116a04a004e7171 \" >[vc_single_image image=&#8221;1060&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1061&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1062&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-41023521116a04a004e7171').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-41023521116a04a004e7171').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-21394366606a04a004e72b2\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-23250292316a04a004e729d \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-23250292316a04a004e729d').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-23250292316a04a004e729d').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-4016\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab5\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab5\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6728 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >FOTOGALLERY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-19475429496a04a004e6d5a\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-42068090126a04a004e6d44 \" >[vc_single_image image=&#8221;1060&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1061&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1062&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-42068090126a04a004e6d44').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-42068090126a04a004e6d44').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab6\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab6\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6728 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >VIDEO<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab7\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab7\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6728 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >MAKING OF<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-32470275666a04a004e6e02\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-28469181206a04a004e6deb \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-28469181206a04a004e6deb').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-28469181206a04a004e6deb').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597824148186{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597916374040{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-lg&#8221;]<div id=\"advanced-tabs-desc-wrap-2604\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-8428 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601308208982-0-8\"  id=\"1601308208982-0-8\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8428 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">OPERA<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#1601308209163-0-6\"  id=\"1601308209163-0-6\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8428 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">DESIGNER<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#1601308209638-0-3\"  id=\"1601308209638-0-3\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8428 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">PRODUCTION<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601308210057-0-0\"  id=\"1601308210057-0-0\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8428 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">CATEGORY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-2604 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]L\u2019installazione \u201cWalls\u201d si domanda come la \u201cframmentazione\u201d sviluppi spazi a diverse scale, dalle micro alle macro. Fin dai tempi di <strong>Roma<\/strong>, complessa citt\u00e0 dell\u2019Impero Romano, le citt\u00e0 si sono sviluppate mediante suddivisioni per crescita e stratificazioni.[\/vc_column_text][vc_custom_heading text=&#8221;L\u2019EMERGERE DELLA \u201cPROPRIET\u00c0\u201d COMINCI\u00d2 CON LE \u201cDOPPIE MURA\u201d DELL\u2019IMPERATORE NERONE, CHE FINIRONO PER DIVENTARE LA BASE DEI TERRENI EDIFICABILI&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Analogamente possiamo tracciare l\u2019emergere dei minerali di marmo attraverso i processi di frammentazione e stratificazione. L\u2019installazione si accosta al marmo come<strong> linguaggio topografico<\/strong>, stratificando i cristalli da sola grazie ad una struttura suddivisoria. Inoltre, mira a rivelare le suddivisioni del marmo e la strategia genera una trama a pareti sottili sulla superficie in modo da simulare in <em>microscala<\/em> l\u2019essenza stessa della citt\u00e0. Le mura realizzano un confine, una rappresentazione dello spazio, o addirittura lo spazio stesso fondato dalla riconsiderazione del concetto di parete, elemento principale dell\u2019edificio.[\/vc_column_text]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;ALPER DERINBOGAZ&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Vincitore dell\u2019International Plan Award for <em>Innovative Architecture<\/em>, riconosciuto come \u201carchitetto emergente e influente\u201d, Derinbogaz si \u00e8 laureato all\u2019ITU, ha studiato presso l\u2019UCLA e si \u00e8 aggiudicato una <strong>Borsa di studio Fulbright<\/strong>. Ha vinto il Graduate Award per i suoi studi di Master e ha rappresentato la Turchia alla 14a Biennale di Architettura di Venezia nel suo anno di debutto presso il Padiglione turco nel 2014. Per i suoi recenti lavori gli \u00e8 stato assegnato l\u2019<strong>Architizer A+Award 2015<\/strong>. Attualmente insegna Design all\u2019ITU e dirige le attivit\u00e0 professionali del suo studio. Vincitore dell\u2019International Plan Award for Innovative Architecture, riconosciuto come \u201carchitetto emergente e influente\u201d, Derinbogaz si \u00e8 laureato all\u2019ITU, ha studiato presso l\u2019UCLA e si \u00e8 aggiudicato una Borsa di studio Fulbright. Ha vinto il Graduate Award per i suoi studi di Master e ha rappresentato la Turchia alla 14a Biennale di Architettura di Venezia nel suo anno di debutto presso il Padiglione turco nel 2014. Per i suoi recenti lavori gli \u00e8 stato assegnato l\u2019Architizer A+Award 2015. Attualmente insegna Design all\u2019ITU e dirige le attivit\u00e0 professionali del suo studio.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;691&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fsalonarchitects.com%2Fabout%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fsalonarchitects.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; linkedin&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.linkedin.com%2Fcompany%2Fsalon2%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;GARFAGNANA INNOVAZIONE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;694&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Primo Tonini 82\/A<br \/>\n55034 Gramolazzo, Lucca, Italia<br \/>\nTel.\/Fax +39 0583.390946<br \/>\n<a href=\"mailto:info@garfagnanainnovazione.it\">info@garfagnanainnovazione.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.garfagnanainnovazione.it%2Fit||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]Curata da <em>Luca Molinari<\/em><\/p>\n<p>La pietra negli ultimi anni \u00e8 divenuta protagonista di numerose opere emblematiche della contemporaneit\u00e0 e ha inciso in modo significativo sul pensiero dei progettisti e sull\u2019evoluzione dei linguaggi architettonici attuali.\u00a0L\u2019introduzione di recenti sofisticate tecnologie di trasformazione ne ha inoltre permesso un<strong> impiego sostenibile<\/strong> favorendo il raggiungimento di nuovi livelli espressivi. La mostra\u00a0<em>Soul of City<\/em> indaga, attraverso la pietra, possibili visioni della citt\u00e0 contemporanea. \u00c8 un progetto di ricerca sull\u2019utilizzo della pietra che prende in prestito il tema del <strong>Congresso UIA 2017<\/strong> a Seoul. Sette studi internazionali di progettazione abbinati ad aziende del comparto marmifero italiano sfidano la materia da un punto di vista architettonico per rappresentare la propria idea di citt\u00e0.[\/vc_column_text]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-2604\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601308208982-0-8\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601308208982-0-8\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8428 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >OPERA<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]L\u2019installazione \u201cWalls\u201d si domanda come la \u201cframmentazione\u201d sviluppi spazi a diverse scale, dalle micro alle macro. Fin dai tempi di <strong>Roma<\/strong>, complessa citt\u00e0 dell\u2019Impero Romano, le citt\u00e0 si sono sviluppate mediante suddivisioni per crescita e stratificazioni.[\/vc_column_text][vc_custom_heading text=&#8221;L\u2019EMERGERE DELLA \u201cPROPRIET\u00c0\u201d COMINCI\u00d2 CON LE \u201cDOPPIE MURA\u201d DELL\u2019IMPERATORE NERONE, CHE FINIRONO PER DIVENTARE LA BASE DEI TERRENI EDIFICABILI&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Analogamente possiamo tracciare l\u2019emergere dei minerali di marmo attraverso i processi di frammentazione e stratificazione. L\u2019installazione si accosta al marmo come<strong> linguaggio topografico<\/strong>, stratificando i cristalli da sola grazie ad una struttura suddivisoria. Inoltre, mira a rivelare le suddivisioni del marmo e la strategia genera una trama a pareti sottili sulla superficie in modo da simulare in <em>microscala<\/em> l\u2019essenza stessa della citt\u00e0. Le mura realizzano un confine, una rappresentazione dello spazio, o addirittura lo spazio stesso fondato dalla riconsiderazione del concetto di parete, elemento principale dell\u2019edificio.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601308209163-0-6\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601308209163-0-6\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8428 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >DESIGNER<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;ALPER DERINBOGAZ&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Vincitore dell\u2019International Plan Award for <em>Innovative Architecture<\/em>, riconosciuto come \u201carchitetto emergente e influente\u201d, Derinbogaz si \u00e8 laureato all\u2019ITU, ha studiato presso l\u2019UCLA e si \u00e8 aggiudicato una <strong>Borsa di studio Fulbright<\/strong>. Ha vinto il Graduate Award per i suoi studi di Master e ha rappresentato la Turchia alla 14a Biennale di Architettura di Venezia nel suo anno di debutto presso il Padiglione turco nel 2014. Per i suoi recenti lavori gli \u00e8 stato assegnato l\u2019<strong>Architizer A+Award 2015<\/strong>. Attualmente insegna Design all\u2019ITU e dirige le attivit\u00e0 professionali del suo studio. Vincitore dell\u2019International Plan Award for Innovative Architecture, riconosciuto come \u201carchitetto emergente e influente\u201d, Derinbogaz si \u00e8 laureato all\u2019ITU, ha studiato presso l\u2019UCLA e si \u00e8 aggiudicato una Borsa di studio Fulbright. Ha vinto il Graduate Award per i suoi studi di Master e ha rappresentato la Turchia alla 14a Biennale di Architettura di Venezia nel suo anno di debutto presso il Padiglione turco nel 2014. Per i suoi recenti lavori gli \u00e8 stato assegnato l\u2019Architizer A+Award 2015. Attualmente insegna Design all\u2019ITU e dirige le attivit\u00e0 professionali del suo studio.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;691&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fsalonarchitects.com%2Fabout%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fsalonarchitects.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; linkedin&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.linkedin.com%2Fcompany%2Fsalon2%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601308209638-0-3\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601308209638-0-3\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8428 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >PRODUCTION<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;GARFAGNANA INNOVAZIONE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;694&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Primo Tonini 82\/A<br \/>\n55034 Gramolazzo, Lucca, Italia<br \/>\nTel.\/Fax +39 0583.390946<br \/>\n<a href=\"mailto:info@garfagnanainnovazione.it\">info@garfagnanainnovazione.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.garfagnanainnovazione.it%2Fit||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601308210057-0-0\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601308210057-0-0\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-8428 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >CATEGORY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]Curata da <em>Luca Molinari<\/em><\/p>\n<p>La pietra negli ultimi anni \u00e8 divenuta protagonista di numerose opere emblematiche della contemporaneit\u00e0 e ha inciso in modo significativo sul pensiero dei progettisti e sull\u2019evoluzione dei linguaggi architettonici attuali.\u00a0L\u2019introduzione di recenti sofisticate tecnologie di trasformazione ne ha inoltre permesso un<strong> impiego sostenibile<\/strong> favorendo il raggiungimento di nuovi livelli espressivi. La mostra\u00a0<em>Soul of City<\/em> indaga, attraverso la pietra, possibili visioni della citt\u00e0 contemporanea. \u00c8 un progetto di ricerca sull\u2019utilizzo della pietra che prende in prestito il tema del <strong>Congresso UIA 2017<\/strong> a Seoul. Sette studi internazionali di progettazione abbinati ad aziende del comparto marmifero italiano sfidano la materia da un punto di vista architettonico per rappresentare la propria idea di citt\u00e0.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[vc_empty_space]<div id=\"advanced-tabs-desc-wrap-6248\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-1240 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601308217494-0-10\"  id=\"1601308217494-0-10\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1240 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">FOTOGALLERY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#1601308217782-0-2\"  id=\"1601308217782-0-2\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1240 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">VIDEO<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601308217977-0-2\"  id=\"1601308217977-0-2\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1240 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">MAKING OF<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-6248 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-37388577076a04a004e7d60\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-15903111336a04a004e7d4b \" >[vc_single_image image=&#8221;1060&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1061&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1062&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-15903111336a04a004e7d4b').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-15903111336a04a004e7d4b').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-36969108476a04a004e7e93\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-554061196a04a004e7e7e \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-554061196a04a004e7e7e').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-554061196a04a004e7e7e').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-6248\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601308217494-0-10\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601308217494-0-10\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1240 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >FOTOGALLERY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-22788446266a04a004e7943\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-22952404606a04a004e792d \" >[vc_single_image image=&#8221;1060&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1061&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;1062&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-22952404606a04a004e792d').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-22952404606a04a004e792d').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601308217782-0-2\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601308217782-0-2\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1240 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >VIDEO<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601308217977-0-2\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601308217977-0-2\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1240 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >MAKING OF<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-27169939026a04a004e79e5\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-32294420366a04a004e79cf \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-32294420366a04a004e79cf').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-32294420366a04a004e79cf').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1597757321777{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597757327347{margin-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1597912466508{margin-bottom: 10px !important;}&#8221;][\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_type=&#8221;bg_color&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1597765947427{padding-top: 10px !important;padding-bottom: 10px !important;}&#8221; bg_color_value=&#8221;#000000&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597766022185{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee226a8be0ed&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597765784345{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee2275481d8a&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597824148186{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916384011{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916390943{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221;&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-311","page","type-page","status-publish","hentry","description-off"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/pages\/311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/comments?post=311"}],"version-history":[{"count":0,"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/pages\/311\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/media?parent=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}