{"id":263,"date":"2020-09-22T11:32:16","date_gmt":"2020-09-22T09:32:16","guid":{"rendered":"http:\/\/www.portfolio.marmomac.com\/erodescape\/"},"modified":"2020-09-28T17:16:19","modified_gmt":"2020-09-28T15:16:19","slug":"new-karnak","status":"publish","type":"page","link":"https:\/\/www.marmomac.com\/portfolio\/new-karnak\/","title":{"rendered":"New karnak"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1597757321777{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597757327347{margin-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1597912466508{margin-bottom: 10px !important;}&#8221;]<div data-post-id=\"12\" class=\"insert-page insert-page-12 \"><style type=\"text\/css\" data-type=\"vc_custom-css\">#titletist{\r\n    letter-spacing: 1px;\r\n}\r\n#linktitle{\r\n    letter-spacing: 1px;\r\n    font-weight:600;\r\n}<\/style><div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;The Italian Stone Theatre&#8221; font_container=&#8221;tag:h1|font_size:18|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_custom_heading text=&#8221;&gt; project&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.marmomac.com%2Fportfolio%2Fproject%2F|title:%3E%20project||&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_custom_heading text=&#8221;&gt; magazine&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2Fmagazine%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_custom_heading text=&#8221;&gt; marmomac.com&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2F|title:%3E%20marmomac.com|target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column offset=&#8221;vc_hidden-lg&#8221;][vc_row_inner][vc_column_inner][vc_custom_heading text=&#8221;The Italian Stone Theatre&#8221; font_container=&#8221;tag:h1|font_size:18|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; project&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.marmomac.com%2Fportfolio%2Fproject%2F|title:%3E%20project||&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; magazine&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2Fmagazine%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; marmomac.com&#8221; font_container=&#8221;tag:h2|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.marmomac.com%2F|title:%3E%20marmomac.com|target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div><\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_type=&#8221;bg_color&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1597765947427{padding-top: 10px !important;padding-bottom: 10px !important;}&#8221; bg_color_value=&#8221;#000000&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597766022185{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee226a8be0ed&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597765784345{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee2275481d8a&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597824148186{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916384011{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;]<div id=\"advanced-tabs-desc-wrap-4931\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-1739 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab1\"  id=\"tab1\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1739 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">OPERA<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#tab2\"  id=\"tab2\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1739 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">DESIGNER<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#tab3\"  id=\"tab3\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1739 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">PRODUCTION<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab4\"  id=\"tab4\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1739 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">CATEGORY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-4931 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]L\u2019installazione <strong>New Karnak<\/strong> ha la forma di un cuneo lapideo sghembo, attraversato da gradini in pietra di <strong>Vicenza Bianco Avorio<\/strong> che salgono verso uno stretto taglio di luce e si specchiano in un pavimento levigato.[\/vc_column_text][vc_custom_heading text=&#8221;ESSA VUOLE METTERE IN SCENA IL \u201cGRADO ZERO\u201d DELLA COSTRUZIONE IN PIETRA PER IMPILAMENTO&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Al contempo evocare \u2013 attraverso l\u2019<strong>artificio ambiguo<\/strong> del modello in scala \u2013 le \u201cnuove piramidi\u201d delle metropoli contemporanee, proiettate alla ricerca di un futuro possibile.[\/vc_column_text]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;CINO ZUCCHI&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Nato a Milano nel 1955, ha conseguito il <strong>B.S.A.D presso l\u2019M.I.T.<\/strong> nel 1978 e la Laurea in Architettura presso il Politecnico di Milano nel 1979. \u00c8 Professore Ordinario di Composizione Architettonica e Urbana presso la I Facolt\u00e0 di Architettura di Milano \u201cArchitettura e Societ\u00e0\u201d e docente nel Dottorato di Progettazione Architettonica e Urbana. \u00c8 stato \u201c<em>visiting professor<\/em>\u201d presso la <strong>Syracuse University di Firenze<\/strong> nel 1989 e nel 1990 e presso l\u2019ETH di Zurigo nel 1997 e 1998. Ha partecipato all\u2019organizzazione e all\u2019allestimento della XV, XVI, XVIII e XIX Triennale di Milano e nel 2014 \u00e8 stato Curatore del Padiglione Italia alla <strong>Biennale Architettura di Venezia<\/strong>. Con lo studio Cino Zucchi Architetti ha realizzato il ridisegno dell\u2019area dismessa della ex-Junghans a Venezia, il progetto di residenze ed uffici per l\u2019ex area Alfa Romeo-Portello a Milano, la ristrutturazione e l\u2019ampliamento del Museo dell\u2019Automobile di Torino e gli edifici residenziali nell\u2019area Ex mercato Ortofrutticolo a Bologna.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;465&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:http%3A%2F%2Fwww.zucchiarchitetti.com%2Fcz%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:http%3A%2F%2Fwww.zucchiarchitetti.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; facebook&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:https%3A%2F%2Fwww.facebook.com%2FCinoZucchiArchitetti%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;GRASSI PIETRE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;468&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Madonetta, 2<br \/>\n36024 Nanto (Vicenza) \u2013 Italy<br \/>\nTel. +39.0444.639092<br \/>\nFax +39.0444.730071<br \/>\n<a href=\"mailto:info@grassipietre.it\">info@grassipietre.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fgrassipietre.it%2F||target:%20_blank|&#8221; el_id=&#8221;linktitle&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]a cura di <em>Vincenzo Pavan<\/em><\/p>\n<p><strong>Lithic Vertigo<\/strong> \u00e8 una mostra di sperimentazione e creativit\u00e0 sull\u2019uso della pietra, finalizzata a promuovere il \u201cMade in Italy\u201d litico attraverso l\u2019interpretazione di prestigiosi progettisti internazionali. L\u2019atto del salire, nell\u2019architettura come negli spazi urbani, ha sempre costituito una sfida intrigante per gli architetti, talvolta una prova di abilit\u00e0 per dimostrare le capacit\u00e0 tecniche e creative del progettista. Sia nel passato che in epoca contemporanea la pietra, pi\u00f9 di altri materiali, si \u00e8 rivelata particolarmente adatta a sperimentazioni su questo tema. Con materiali litici si sono infatti realizzate le scale pi\u00f9 ingegnose e ricche di espressivit\u00e0 plastica, dal barocco al liberty, dal classico al moderno. Allo stesso modo questo materiale si presta a modellare rampe, percorsi e superfici inclinate, strutturalmente complesse e visivamente \u201cvertiginose\u201d.<\/p>\n<p>La mostra intende produrre nuove esperienze progettuali e inedite interpretazioni dei materiali lapidei con l\u2019apporto di architetti e designer di notoriet\u00e0 internazionale e aziende italiane del settore lapideo aperte alla sperimentazione. Dalla loro collaborazione \u00e8 nato lo stimolo a cercare nuove forme e soluzioni creative per elementi fondamentali della costruzione e a scoprire inedite qualit\u00e0 tecnico-espressive di un materiale di cos\u00ec antica tradizione.[\/vc_column_text]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-4931\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab1\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab1\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1739 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >OPERA<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]L\u2019installazione <strong>New Karnak<\/strong> ha la forma di un cuneo lapideo sghembo, attraversato da gradini in pietra di <strong>Vicenza Bianco Avorio<\/strong> che salgono verso uno stretto taglio di luce e si specchiano in un pavimento levigato.[\/vc_column_text][vc_custom_heading text=&#8221;ESSA VUOLE METTERE IN SCENA IL \u201cGRADO ZERO\u201d DELLA COSTRUZIONE IN PIETRA PER IMPILAMENTO&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Al contempo evocare \u2013 attraverso l\u2019<strong>artificio ambiguo<\/strong> del modello in scala \u2013 le \u201cnuove piramidi\u201d delle metropoli contemporanee, proiettate alla ricerca di un futuro possibile.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab2\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab2\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1739 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >DESIGNER<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;CINO ZUCCHI&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Nato a Milano nel 1955, ha conseguito il <strong>B.S.A.D presso l\u2019M.I.T.<\/strong> nel 1978 e la Laurea in Architettura presso il Politecnico di Milano nel 1979. \u00c8 Professore Ordinario di Composizione Architettonica e Urbana presso la I Facolt\u00e0 di Architettura di Milano \u201cArchitettura e Societ\u00e0\u201d e docente nel Dottorato di Progettazione Architettonica e Urbana. \u00c8 stato \u201c<em>visiting professor<\/em>\u201d presso la <strong>Syracuse University di Firenze<\/strong> nel 1989 e nel 1990 e presso l\u2019ETH di Zurigo nel 1997 e 1998. Ha partecipato all\u2019organizzazione e all\u2019allestimento della XV, XVI, XVIII e XIX Triennale di Milano e nel 2014 \u00e8 stato Curatore del Padiglione Italia alla <strong>Biennale Architettura di Venezia<\/strong>. Con lo studio Cino Zucchi Architetti ha realizzato il ridisegno dell\u2019area dismessa della ex-Junghans a Venezia, il progetto di residenze ed uffici per l\u2019ex area Alfa Romeo-Portello a Milano, la ristrutturazione e l\u2019ampliamento del Museo dell\u2019Automobile di Torino e gli edifici residenziali nell\u2019area Ex mercato Ortofrutticolo a Bologna.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;465&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:http%3A%2F%2Fwww.zucchiarchitetti.com%2Fcz%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:http%3A%2F%2Fwww.zucchiarchitetti.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; facebook&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;linktitle&#8221; link=&#8221;url:https%3A%2F%2Fwww.facebook.com%2FCinoZucchiArchitetti%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab3\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab3\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1739 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >PRODUCTION<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;GRASSI PIETRE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; el_id=&#8221;titletabbig&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;468&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Madonetta, 2<br \/>\n36024 Nanto (Vicenza) \u2013 Italy<br \/>\nTel. +39.0444.639092<br \/>\nFax +39.0444.730071<br \/>\n<a href=\"mailto:info@grassipietre.it\">info@grassipietre.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fgrassipietre.it%2F||target:%20_blank|&#8221; el_id=&#8221;linktitle&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab4\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab4\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-1739 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >CATEGORY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]a cura di <em>Vincenzo Pavan<\/em><\/p>\n<p><strong>Lithic Vertigo<\/strong> \u00e8 una mostra di sperimentazione e creativit\u00e0 sull\u2019uso della pietra, finalizzata a promuovere il \u201cMade in Italy\u201d litico attraverso l\u2019interpretazione di prestigiosi progettisti internazionali. L\u2019atto del salire, nell\u2019architettura come negli spazi urbani, ha sempre costituito una sfida intrigante per gli architetti, talvolta una prova di abilit\u00e0 per dimostrare le capacit\u00e0 tecniche e creative del progettista. Sia nel passato che in epoca contemporanea la pietra, pi\u00f9 di altri materiali, si \u00e8 rivelata particolarmente adatta a sperimentazioni su questo tema. Con materiali litici si sono infatti realizzate le scale pi\u00f9 ingegnose e ricche di espressivit\u00e0 plastica, dal barocco al liberty, dal classico al moderno. Allo stesso modo questo materiale si presta a modellare rampe, percorsi e superfici inclinate, strutturalmente complesse e visivamente \u201cvertiginose\u201d.<\/p>\n<p>La mostra intende produrre nuove esperienze progettuali e inedite interpretazioni dei materiali lapidei con l\u2019apporto di architetti e designer di notoriet\u00e0 internazionale e aziende italiane del settore lapideo aperte alla sperimentazione. Dalla loro collaborazione \u00e8 nato lo stimolo a cercare nuove forme e soluzioni creative per elementi fondamentali della costruzione e a scoprire inedite qualit\u00e0 tecnico-espressive di un materiale di cos\u00ec antica tradizione.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916390943{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;]<div id=\"advanced-tabs-desc-wrap-7504\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-5547 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab5\"  id=\"tab5\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5547 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">FOTOGALLERY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#tab6\"  id=\"tab6\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5547 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">VIDEO<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#tab7\"  id=\"tab7\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5547 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">MAKING OF<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-7504 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-8685209656a049fade0181\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-22828191346a049fade016c \" >[vc_single_image image=&#8221;865&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;867&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-22828191346a049fade016c').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-22828191346a049fade016c').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-9920007156a049fade02aa\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-38308288126a049fade0295 \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-38308288126a049fade0295').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-38308288126a049fade0295').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-7504\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab5\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab5\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5547 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >FOTOGALLERY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-27165574596a049faddfd66\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-35400166986a049faddfd50 \" >[vc_single_image image=&#8221;865&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;867&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-35400166986a049faddfd50').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-35400166986a049faddfd50').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab6\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab6\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5547 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >VIDEO<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"tab7\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#tab7\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-5547 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >MAKING OF<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-4381286696a049faddfe0c\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-1176451526a049faddfdf6 \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-1176451526a049faddfdf6').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-1176451526a049faddfdf6').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597824148186{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597916374040{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-lg&#8221;]<div id=\"advanced-tabs-desc-wrap-9825\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-6726 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601306158845-0-3\"  id=\"1601306158845-0-3\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6726 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">OPERA<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#1601306158999-0-1\"  id=\"1601306158999-0-1\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6726 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">DESIGNER<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#1601306159411-0-5\"  id=\"1601306159411-0-5\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6726 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">PRODUCTION<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601306159786-0-4\"  id=\"1601306159786-0-4\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6726 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">CATEGORY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-9825 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]L\u2019installazione <strong>New Karnak<\/strong> ha la forma di un cuneo lapideo sghembo, attraversato da gradini in pietra di <strong>Vicenza Bianco Avorio<\/strong> che salgono verso uno stretto taglio di luce e si specchiano in un pavimento levigato.[\/vc_column_text][vc_custom_heading text=&#8221;ESSA VUOLE METTERE IN SCENA IL \u201cGRADO ZERO\u201d DELLA COSTRUZIONE IN PIETRA PER IMPILAMENTO&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Al contempo evocare \u2013 attraverso l\u2019<strong>artificio ambiguo<\/strong> del modello in scala \u2013 le \u201cnuove piramidi\u201d delle metropoli contemporanee, proiettate alla ricerca di un futuro possibile.[\/vc_column_text]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;CINO ZUCCHI&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Nato a Milano nel 1955, ha conseguito il <strong>B.S.A.D presso l\u2019M.I.T.<\/strong> nel 1978 e la Laurea in Architettura presso il Politecnico di Milano nel 1979. \u00c8 Professore Ordinario di Composizione Architettonica e Urbana presso la I Facolt\u00e0 di Architettura di Milano \u201cArchitettura e Societ\u00e0\u201d e docente nel Dottorato di Progettazione Architettonica e Urbana. \u00c8 stato \u201c<em>visiting professor<\/em>\u201d presso la <strong>Syracuse University di Firenze<\/strong> nel 1989 e nel 1990 e presso l\u2019ETH di Zurigo nel 1997 e 1998. Ha partecipato all\u2019organizzazione e all\u2019allestimento della XV, XVI, XVIII e XIX Triennale di Milano e nel 2014 \u00e8 stato Curatore del Padiglione Italia alla <strong>Biennale Architettura di Venezia<\/strong>. Con lo studio Cino Zucchi Architetti ha realizzato il ridisegno dell\u2019area dismessa della ex-Junghans a Venezia, il progetto di residenze ed uffici per l\u2019ex area Alfa Romeo-Portello a Milano, la ristrutturazione e l\u2019ampliamento del Museo dell\u2019Automobile di Torino e gli edifici residenziali nell\u2019area Ex mercato Ortofrutticolo a Bologna.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;465&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.zucchiarchitetti.com%2Fcz%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.zucchiarchitetti.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; facebook&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.facebook.com%2FCinoZucchiArchitetti%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_custom_heading text=&#8221;GRASSI PIETRE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;468&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Madonetta, 2<br \/>\n36024 Nanto (Vicenza) \u2013 Italy<br \/>\nTel. +39.0444.639092<br \/>\nFax +39.0444.730071<br \/>\n<a href=\"mailto:info@grassipietre.it\">info@grassipietre.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fgrassipietre.it%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_column_text]a cura di <em>Vincenzo Pavan<\/em><\/p>\n<p><strong>Lithic Vertigo<\/strong> \u00e8 una mostra di sperimentazione e creativit\u00e0 sull\u2019uso della pietra, finalizzata a promuovere il \u201cMade in Italy\u201d litico attraverso l\u2019interpretazione di prestigiosi progettisti internazionali. L\u2019atto del salire, nell\u2019architettura come negli spazi urbani, ha sempre costituito una sfida intrigante per gli architetti, talvolta una prova di abilit\u00e0 per dimostrare le capacit\u00e0 tecniche e creative del progettista. Sia nel passato che in epoca contemporanea la pietra, pi\u00f9 di altri materiali, si \u00e8 rivelata particolarmente adatta a sperimentazioni su questo tema. Con materiali litici si sono infatti realizzate le scale pi\u00f9 ingegnose e ricche di espressivit\u00e0 plastica, dal barocco al liberty, dal classico al moderno. Allo stesso modo questo materiale si presta a modellare rampe, percorsi e superfici inclinate, strutturalmente complesse e visivamente \u201cvertiginose\u201d.<\/p>\n<p>La mostra intende produrre nuove esperienze progettuali e inedite interpretazioni dei materiali lapidei con l\u2019apporto di architetti e designer di notoriet\u00e0 internazionale e aziende italiane del settore lapideo aperte alla sperimentazione. Dalla loro collaborazione \u00e8 nato lo stimolo a cercare nuove forme e soluzioni creative per elementi fondamentali della costruzione e a scoprire inedite qualit\u00e0 tecnico-espressive di un materiale di cos\u00ec antica tradizione.[\/vc_column_text]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-9825\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601306158845-0-3\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601306158845-0-3\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6726 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >OPERA<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]L\u2019installazione <strong>New Karnak<\/strong> ha la forma di un cuneo lapideo sghembo, attraversato da gradini in pietra di <strong>Vicenza Bianco Avorio<\/strong> che salgono verso uno stretto taglio di luce e si specchiano in un pavimento levigato.[\/vc_column_text][vc_custom_heading text=&#8221;ESSA VUOLE METTERE IN SCENA IL \u201cGRADO ZERO\u201d DELLA COSTRUZIONE IN PIETRA PER IMPILAMENTO&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Al contempo evocare \u2013 attraverso l\u2019<strong>artificio ambiguo<\/strong> del modello in scala \u2013 le \u201cnuove piramidi\u201d delle metropoli contemporanee, proiettate alla ricerca di un futuro possibile.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601306158999-0-1\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601306158999-0-1\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6726 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >DESIGNER<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;CINO ZUCCHI&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_column_text]Nato a Milano nel 1955, ha conseguito il <strong>B.S.A.D presso l\u2019M.I.T.<\/strong> nel 1978 e la Laurea in Architettura presso il Politecnico di Milano nel 1979. \u00c8 Professore Ordinario di Composizione Architettonica e Urbana presso la I Facolt\u00e0 di Architettura di Milano \u201cArchitettura e Societ\u00e0\u201d e docente nel Dottorato di Progettazione Architettonica e Urbana. \u00c8 stato \u201c<em>visiting professor<\/em>\u201d presso la <strong>Syracuse University di Firenze<\/strong> nel 1989 e nel 1990 e presso l\u2019ETH di Zurigo nel 1997 e 1998. Ha partecipato all\u2019organizzazione e all\u2019allestimento della XV, XVI, XVIII e XIX Triennale di Milano e nel 2014 \u00e8 stato Curatore del Padiglione Italia alla <strong>Biennale Architettura di Venezia<\/strong>. Con lo studio Cino Zucchi Architetti ha realizzato il ridisegno dell\u2019area dismessa della ex-Junghans a Venezia, il progetto di residenze ed uffici per l\u2019ex area Alfa Romeo-Portello a Milano, la ristrutturazione e l\u2019ampliamento del Museo dell\u2019Automobile di Torino e gli edifici residenziali nell\u2019area Ex mercato Ortofrutticolo a Bologna.[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_single_image image=&#8221;465&#8243; img_size=&#8221;medium&#8221;][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; zoom bio&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.zucchiarchitetti.com%2Fcz%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:http%3A%2F%2Fwww.zucchiarchitetti.com%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; facebook&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.facebook.com%2FCinoZucchiArchitetti%2F||target:%20_blank|&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601306159411-0-5\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601306159411-0-5\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6726 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >PRODUCTION<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_custom_heading text=&#8221;GRASSI PIETRE&#8221; font_container=&#8221;tag:h5|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#000000&#8243;][vc_single_image image=&#8221;468&#8243; img_size=&#8221;full&#8221;][vc_column_text]<strong>Sede stabilimento:<\/strong><br \/>\nVia Madonetta, 2<br \/>\n36024 Nanto (Vicenza) \u2013 Italy<br \/>\nTel. +39.0444.639092<br \/>\nFax +39.0444.730071<br \/>\n<a href=\"mailto:info@grassipietre.it\">info@grassipietre.it<\/a>[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text=&#8221;&gt; site&#8221; font_container=&#8221;tag:h5|font_size:14|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fgrassipietre.it%2F||target:%20_blank|&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601306159786-0-4\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601306159786-0-4\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6726 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >CATEGORY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_column_text]a cura di <em>Vincenzo Pavan<\/em><\/p>\n<p><strong>Lithic Vertigo<\/strong> \u00e8 una mostra di sperimentazione e creativit\u00e0 sull\u2019uso della pietra, finalizzata a promuovere il \u201cMade in Italy\u201d litico attraverso l\u2019interpretazione di prestigiosi progettisti internazionali. L\u2019atto del salire, nell\u2019architettura come negli spazi urbani, ha sempre costituito una sfida intrigante per gli architetti, talvolta una prova di abilit\u00e0 per dimostrare le capacit\u00e0 tecniche e creative del progettista. Sia nel passato che in epoca contemporanea la pietra, pi\u00f9 di altri materiali, si \u00e8 rivelata particolarmente adatta a sperimentazioni su questo tema. Con materiali litici si sono infatti realizzate le scale pi\u00f9 ingegnose e ricche di espressivit\u00e0 plastica, dal barocco al liberty, dal classico al moderno. Allo stesso modo questo materiale si presta a modellare rampe, percorsi e superfici inclinate, strutturalmente complesse e visivamente \u201cvertiginose\u201d.<\/p>\n<p>La mostra intende produrre nuove esperienze progettuali e inedite interpretazioni dei materiali lapidei con l\u2019apporto di architetti e designer di notoriet\u00e0 internazionale e aziende italiane del settore lapideo aperte alla sperimentazione. Dalla loro collaborazione \u00e8 nato lo stimolo a cercare nuove forme e soluzioni creative per elementi fondamentali della costruzione e a scoprire inedite qualit\u00e0 tecnico-espressive di un materiale di cos\u00ec antica tradizione.[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[vc_empty_space]<div id=\"advanced-tabs-desc-wrap-5723\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#ffffff\" data-titlecolor=\"#aaabaf\" data-fullheight=\"off\"\n data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"None\"\ndata-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\"  data-respmode=\"Accordion\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-6807 class=\"ult_tabmenu style1 Style_4\" style=\"color:#000000;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-left-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601306166754-0-0\"  id=\"1601306166754-0-0\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6807 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">FOTOGALLERY<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#1601306166981-0-9\"  id=\"1601306166981-0-9\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6807 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">VIDEO<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li ult_tab_style_4 \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#ffffff;border-color:#000000;border-width:1px;border-style:solid;border-top-right-radius:0px;\">\n\t\t\t\t\t<a href=\"#1601306167158-0-5\"  id=\"1601306167158-0-5\"  style=\"color:#aaabaf;;   \" class=\"ult_a ult_tab_style_4 \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6807 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">MAKING OF<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-5723 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"background-color:#ffffff;color:#000000;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-10629653576a049fade0d4f\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-3670038456a049fade0d3a \" >[vc_single_image image=&#8221;865&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;867&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-3670038456a049fade0d3a').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-3670038456a049fade0d3a').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-7138095906a049fade0e77\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-29436315246a049fade0e62 \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-29436315246a049fade0e62').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-29436315246a049fade0e62').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-5723\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#aaabaf\"  data-titlebg=\"#ffffff\"\n     data-titlehoverbg=\"#ffffff\" data-titlehovercolor=\"#aaabaf\" data-animation=\"None\"\n     data-activetitle=\"#000000\" data-activeicon=\"\" data-activebg=\"#ffffff\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601306166754-0-0\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601306166754-0-0\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6807 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >FOTOGALLERY<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-5975061516a049fade093e\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-12265099606a049fade0928 \" >[vc_single_image image=&#8221;865&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;867&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-12265099606a049fade0928').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-12265099606a049fade0928').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601306166981-0-9\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601306166981-0-9\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6807 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >VIDEO<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=i3grNlx0X1I&#8221; align=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1601306167158-0-5\" style=\"color:#aaabaf;;background-color:#ffffff;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;border-bottom-color:#000000;border-bottom-width:1px;border-bottom-style:solid;\" href=\"#1601306167158-0-5\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-6807 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >MAKING OF<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#ffffff;color:#000000;\">\n\t\t\t\t               [vc_empty_space][vc_row_inner][vc_column_inner]<div id=\"ult-carousel-17359877656a049fade09e0\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-18880006796a049fade09ca \" >[vc_single_image image=&#8221;140&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;141&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;][vc_single_image image=&#8221;142&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221; image_hovers=&#8221;false&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-18880006796a049fade09ca').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-18880006796a049fade09ca').slick({dots: true,autoplay: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\t\tslidesToScroll: 1\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#000000;\" class=\"ultsl-checkbox-unchecked\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#ffffff\"><\/div>-->\n<\/div>\n\n<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1597757321777{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597757327347{margin-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1597912466508{margin-bottom: 10px !important;}&#8221;][\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; bg_type=&#8221;bg_color&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1597765947427{padding-top: 10px !important;padding-bottom: 10px !important;}&#8221; bg_color_value=&#8221;#000000&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597766022185{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee226a8be0ed&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597765784345{padding-top: 0px !important;}&#8221;][vc_acf field_group=&#8221;17&#8243; field_from_17=&#8221;field_5ee2275481d8a&#8221; el_class=&#8221;titlemostra&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597824148186{padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916384011{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1597916390943{padding-top: 0px !important;}&#8221; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221;&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-263","page","type-page","status-publish","hentry","description-off"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/pages\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":0,"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/pages\/263\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marmomac.com\/portfolio\/wp-json\/wp\/v2\/media?parent=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}